{"id":8949,"date":"2026-02-05T15:06:10","date_gmt":"2026-02-05T14:06:10","guid":{"rendered":"https:\/\/mahous.com\/?p=8949"},"modified":"2026-03-17T00:58:53","modified_gmt":"2026-03-16T23:58:53","slug":"kiara-nikkei-el-nuevo-restaurant-bar-cool-que-se-5","status":"publish","type":"post","link":"https:\/\/mahous.com\/index.php\/2026\/02\/05\/kiara-nikkei-el-nuevo-restaurant-bar-cool-que-se-5\/","title":{"rendered":"Kiara Nikkei: el nuevo restaurant-bar cool que se toma las noches santiaguinas"},"content":{"rendered":"<div id=\"toc\" style=\"background: #f9f9f9;border: 1px solid #aaa;display: table;margin-bottom: 1em;padding: 1em;width: 350px;\">\n<p class=\"toctitle\" style=\"font-weight: 700;text-align: center;\">Content<\/p>\n<ul class=\"toc_list\">\n<li><a href=\"#toc-0\">Servicio atento y ambiente acogedor<\/a><\/li>\n<li><a href=\"#toc-1\">Mojito sabores<\/a><\/li>\n<li><a href=\"#toc-2\">PISCO<\/a><\/li>\n<li><a href=\"#toc-4\">Havana 7 a\u00f1os<\/a><\/li>\n<\/ul>\n<\/div>\n<p>Tanqueray Ten, syrup de ar\u00e1ndanos, mermelada de rosa mosqueta y espuma de manzana verde, jengibre y Ramazzotti. Gin macerado con t\u00e9 Mariposa azul, Malfy pomelo, licor de mantequilla, pulpa de pi\u00f1a, zumo de lim\u00f3n. La dulzura del licor de sand\u00eda y frutilla en un encuentro c\u00edtrico y elegante con pisco, t\u00e9 de frutos rojos y Chambord. Cl\u00e1sico saltado de versi\u00f3n vegetariano con tofu salteado, con papas bast\u00f3n en plancha caliente, con toques de salsa huancaina. De malaya de cerdo a la parrilla en barbecue detonkatsu acompa\u00f1ada de criolla.<\/p>\n<h2 id=\"toc-0\">Servicio atento y ambiente acogedor<\/h2>\n<p>4 unidades en taquera, relleno de champi\u00f1on salteado en hoisin, salsa de alcachofa ahumada y shishimi. Finos cortes de <a href=\"https:\/\/www.sushinikkei.cl\/\">delivery sushi<\/a> Salm\u00f3n en tiradito, con esferificaciones de katsuo y dressing salsa ponzu Gyozas de cerdo de cocci\u00f3n lenta, rellenas de carne desmechada y cebolla caramelizada, glaseadas con salsa tonkatsu, acompa\u00f1adas de huanca\u00edna y punto de gel.<\/p>\n<h3 id=\"toc-1\">Mojito sabores<\/h3>\n<p>Ron, menta, lim\u00f3n, syrup simple, sellado con agua gasificada, opcional maracuya &#8211; mango &#8211; frutilla &#8211; frambueza Jos\u00e9 Cuervo especial, triple sec, lim\u00f3n y syrup simple. Gin, licor de cassis, lim\u00f3n y syrup simple.<\/p>\n<h3 id=\"toc-2\">PISCO<\/h3>\n<ul>\n<li>Cl\u00e1sico pollo crocante japon\u00e9s marinado, acompa\u00f1ado de mayonesa de lemongrass y unagui.<\/li>\n<li>De malaya de cerdo a la parrilla en barbecue detonkatsu acompa\u00f1ada de criolla.<\/li>\n<li>Disaronno, Alto del Carmen 40\u00b0 transparente, zumo de lim\u00f3n, syrup simple, naranja, Amargo de Angostura, alb\u00famina.<\/li>\n<li>Ron, menta, lim\u00f3n, syrup simple, sellado con agua gasificada, opcional maracuya &#8211; mango &#8211; frutilla &#8211; frambueza<\/li>\n<\/ul>\n<p>La cocina Nikkei nunca deja de sorprender, por la intensidad de sus sabores, sus presentaciones y\u00a0 estilo, donde se juntan,\u00a0 pero no mezclan,\u00a0 las\u00a0 t\u00e9cnicas de la\u00a0 cocina japonesa con esos ya conocidos sabores peruanos; pero que en KIARA Nikkei, se encuentran inmersos dentro de un ambiente tan m\u00edstico como la pen\u00ednsula de Yucat\u00e1n, algo as\u00ed como\u00a0 Tulum\u2026 \u00bflisto para viajar?. Disaronno, Alto del Carmen 40\u00b0 transparente, zumo de lim\u00f3n, syrup simple, naranja, Amargo de Angostura, alb\u00famina. 4 unidades de taco rellenos de salm\u00f3n, aceite de jengibre, palta asada, gel de mango y salsa acevichada 5 dumplings rellenos con mix de verduras y trilog\u00eda de setas, acompa\u00f1ado de salsa huaincaina y salsa de la casa<\/p>\n<p>Mizumi Nikkei, el primer bar-restaurante nikkei de la ciudad, combina lo mejor de la cocina peruano-japonesa con una propuesta de cocteler\u00eda de autor en un ambiente que invita a disfrutar y compartir. Cuando se elige un lugar donde ir, siempre se busca un buen ambiente, calidad de servicio, una barra diversa y de alto nivel, tanto en\u00a0 productos como en\u00a0 preparaci\u00f3n, gastronom\u00eda que sorprenda, buena m\u00fasica y ese algo m\u00e1s que,\u00a0 de seguro, se encuentra en este restaurante-bar, una propuesta que destaca entre las aperturas 2022. Roll envuelto en salm\u00f3n spicy, masago, ceboll\u00edn, mix de semillas, sriracha, pisco en cacho de cabra, relleno de camar\u00f3n, queso crema y palta.<\/p>\n<h2 id=\"toc-3\">Ginger mint lemonade<\/h2>\n<p>Con ingredientes frescos y una cuidada preparaci\u00f3n, cada bocado es una explosi\u00f3n de sabores que te transportar\u00e1 directamente a Jap\u00f3n y Per\u00fa. Los clientes de Nikkei Bar destacan la calidad y frescura de sus platos de sushi. Ubicado en Urdaneta Kalea, 14, este restaurante de sushi ha conquistado el paladar de sus comensales con su exquisita fusi\u00f3n peruano-japonesa. Si est\u00e1s buscando un lugar para disfrutar de sushi de calidad en Donostia-San Sebastian, no puedes perderte Nikkei Bar.<\/p>\n<p>Doble medida de Pisco, lim\u00f3n, syrup simple y alb\u00famina. Picante, ahumado y vibrante, coronado con camar\u00f3n y cebolla perla flambeados. Gin de la casa, campari, vermouth rosso, lim\u00f3n, syrup simple y albumina.<\/p>\n<p>Heineken, leche de tigre nikkei con aji verde, rojo y jengibre en suave picor, finalizado con sal. Salsa inglesa, tabasco, lim\u00f3n, borde de merk\u00e9n ahumado y sal. Refrescante giro al cl\u00e1sico Gin &amp; Tonic, con notas herbales de t\u00e9, la dulzura \u00fanica de la miel de palma y un final burbujeante de ginger ale. Un twist picante al whisky con notas frutales de pera y pi\u00f1a, potenciado por el pisco Alto del Carmen en soluci\u00f3n salina<\/p>\n<h3 id=\"toc-4\">Havana 7 a\u00f1os<\/h3>\n<p>Una fusi\u00f3n exquisita de tamari (salsa de soja japonesa) y aceite verde y palta gratinada que realzan la textura suave del pescado. Brunoise de lomo liso condimentado con mostaza encurtida, cebolla, alcaparra, pepinillo y mix encurtidos, aceite vegetal, cilantro, gel de yema curada y acompa\u00f1ado de tostadas artesanales. Adem\u00e1s de la calidad de sus platos, en Nikkei Bar encontrar\u00e1s una amplia variedad de opciones para todos los gustos. No es de extra\u00f1ar que muchos repitan visita una vez prueban la deliciosa comida de este peque\u00f1o restaurante.<\/p>\n<h2 id=\"toc-5\">\u00bfCu\u00e1l es el tel\u00e9fono de contacto de Nikkei Bar?<\/h2>\n<p>Coctel preparado con horchata de coco, dash de lim\u00f3n, limoncello de la casa y ron mariposa. Cocktail a base de pisco Esp\u00edritu de los Andes, licor Araucano, zumo de pomelo, maracuy\u00e1 y terminaci\u00f3n de syrup de canela. Vino tinto, vermouth rosso, mistral apple, bitter de cardamomo, syrup de pera, zumo de lim\u00f3n y naranja. C\u00f3ctel Ron Havana 7 a\u00f1os, syrup Falernum, horchata de coco, maracuy\u00e1, zumo de lim\u00f3n. Jugoso lomo liso acompa\u00f1ado de chimichurri artesanal y una deliciosa salsa batayaki (mantequilla con soja) para un toque de sabor irresistible. Salm\u00f3n batayaki sobre de arroz al aji amarillo, con mariscos flambeados en pisco y toques de lim\u00f3n de pica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Content Servicio atento y ambiente acogedor Mojito sabores PISCO Havana 7 a\u00f1os Tanqueray Ten, syrup de ar\u00e1ndanos, mermelada de rosa mosqueta y espuma de manzana verde, jengibre y Ramazzotti. Gin macerado con t\u00e9 Mariposa azul, Malfy pomelo, licor de mantequilla, pulpa de pi\u00f1a, zumo de lim\u00f3n. La dulzura del licor de sand\u00eda y frutilla en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[],"class_list":["post-8949","post","type-post","status-publish","format-standard","hentry","category-www-sushinikkei-cl"],"_links":{"self":[{"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/posts\/8949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/comments?post=8949"}],"version-history":[{"count":1,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/posts\/8949\/revisions"}],"predecessor-version":[{"id":8950,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/posts\/8949\/revisions\/8950"}],"wp:attachment":[{"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/media?parent=8949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/categories?post=8949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mahous.com\/index.php\/wp-json\/wp\/v2\/tags?post=8949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}